{"id":827,"date":"2020-08-02T14:47:00","date_gmt":"2020-08-02T14:47:00","guid":{"rendered":"https:\/\/www.link-zauberkunst.de\/zauberer\/tann\/"},"modified":"2020-08-02T14:47:00","modified_gmt":"2020-08-02T14:47:00","slug":"tann","status":"publish","type":"post","link":"https:\/\/www.link-zauberkunst.de\/zauberer\/tann\/","title":{"rendered":"Zauberer Tann | &#129351; Werner Link &#10148; Zaubershow \/ &#10003; Zauberk&uuml;nstler &#038; Magier"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\"  style='background-color: #ffffff;background-position: center center;background-repeat: no-repeat;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;'><div class=\"fusion-builder-row fusion-row \"><div  class=\"fusion-layout-column fusion_builder_column fusion_builder_column_1_1 fusion-builder-column-0 fusion-one-full fusion-column-first fusion-column-last 1_1\"  style='margin-top:0px;margin-bottom:20px;'><div class=\"fusion-column-wrapper\" style=\"padding: 0px 0px 0px 0px;background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\"   data-bg-url=\"\"><div class=\"fusion-text\"><h1><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271200%27%20height%3D%27516%27%20viewBox%3D%270%200%201200%20516%27%3E%3Crect%20width%3D%271200%27%20height%3D%273516%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Zauberer.jpg\" alt=\"Zauberer Tann | &#129351; Werner Link &#10148; Zaubershow \/ &#10003; Zauberein\" \/><\/h1>\n<p><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27581%27%20viewBox%3D%270%200%20600%20581%27%3E%3Crect%20width%3D%27600%27%20height%3D%273581%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Zaubervorstellung.jpg\" alt=\"Zaubervorstellung &#038; magische Vorstellungen in  Tann\" \/><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27581%27%20viewBox%3D%270%200%20600%20581%27%3E%3Crect%20width%3D%27600%27%20height%3D%273581%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Zauberkuenstler.jpg\" alt=\"Zauberk&uuml;nstler in  Tann\" \/><\/p>\n<p><strong>&#129351; Werner Link, Ihr &#9989; Zauberk&uuml;nstler &#038; Magier f&uuml;r &#10042; Zauberein, &#9851; Zaubershows, &#9733; Zauberk&uuml;nstler, &#9745;&#65039; Zaubervorstellungen oder &#10041; Zauberk&uuml;nstler &#038; Magier f&uuml;r  &#10004;&#65039; Tann.  &#10084; Wir freuen uns auf Ihren Besuch &#9993; &#10004;.<\/strong><\/p>\n<p><!--more-->\n<img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27400%27%20height%3D%27480%27%20viewBox%3D%270%200%20400%20480%27%3E%3Crect%20width%3D%27400%27%20height%3D%273480%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Zauberkunst.jpg\" alt=\"Zauberkunst \" \/><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27400%27%20height%3D%27480%27%20viewBox%3D%270%200%20400%20480%27%3E%3Crect%20width%3D%27400%27%20height%3D%273480%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Zauberei.jpg\" alt=\"Zauberei f&uuml;r  Tann - Pichl, Pilgram, Ras&ouml;d, Kreil, N&uuml;rnberg, Obending oder &Ouml;dbinder, &Ouml;dweber, Osten\" \/><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27400%27%20height%3D%27480%27%20viewBox%3D%270%200%20400%20480%27%3E%3Crect%20width%3D%27400%27%20height%3D%273480%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Magier.jpg\" alt=\"Magier f&uuml;r  Tann, Reut, Zeilarn, Stammham, Julbach, Wurmannsquick, Kirchdorf (Inn) und Wittibreut, Marktl, Erlbach\n\" \/> <\/p>\n<\/div>\n<div class=\"fusion-tabs fusion-tabs-1 clean horizontal-tabs icon-position-left\"><style type=\"text\/css\">#wrapper .fusion-tabs.fusion-tabs-1.clean .nav-tabs li a.tab-link{border-color:#ffffff;}.fusion-tabs.fusion-tabs-1 .nav-tabs li a.tab-link{background-color:#ffffff;}.fusion-tabs.fusion-tabs-1 .nav-tabs li.active a.tab-link,.fusion-tabs.fusion-tabs-1 .nav-tabs li.active a.tab-link:hover,.fusion-tabs.fusion-tabs-1 .nav-tabs li.active a.tab-link:focus{background-color:#ffffff;}.fusion-tabs.fusion-tabs-1 .nav-tabs li a:hover{background-color:#ffffff;border-top-color:#ffffff;}.fusion-tabs.fusion-tabs-1 .tab-pane{background-color:#ffffff;}.fusion-tabs.fusion-tabs-1 .nav,.fusion-tabs.fusion-tabs-1 .nav-tabs,.fusion-tabs.fusion-tabs-1 .tab-content .tab-pane{border-color:#ffffff;}<\/style><div class=\"nav\"><ul class=\"nav-tabs nav-justified\"><li class=\"active\"><a class=\"tab-link\" data-toggle=\"tab\" id=\"fusion-tab-wernerlink,ihrzaubererundmagier.\" href=\"#tab-e50a5b331449c69db9b\"><h4 class=\"fusion-tab-heading\">Werner Link, Ihr Zauberer und Magier.<\/h4><\/a><\/li><li><a class=\"tab-link\" data-toggle=\"tab\" id=\"fusion-tab-&nbsp;\" href=\"#tab-1852904ea5c591b1979\"><h4 class=\"fusion-tab-heading\">&nbsp;<\/h4><\/a><\/li><li><a class=\"tab-link\" data-toggle=\"tab\" id=\"fusion-tab-&nbsp;\" href=\"#tab-3f5d29b1767f7726075\"><h4 class=\"fusion-tab-heading\">&nbsp;<\/h4><\/a><\/li><\/ul><\/div><div class=\"tab-content\"><div class=\"nav fusion-mobile-tab-nav\"><ul class=\"nav-tabs nav-justified\"><li class=\"active\"><a class=\"tab-link\" data-toggle=\"tab\" id=\"mobile-fusion-tab-wernerlink,ihrzaubererundmagier.\" href=\"#tab-e50a5b331449c69db9b\"><h4 class=\"fusion-tab-heading\">Werner Link, Ihr Zauberer und Magier.<\/h4><\/a><\/li><\/ul><\/div><div class=\"tab-pane fade fusion-clearfix in active\" id=\"tab-e50a5b331449c69db9b\">\n<img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27476%27%20viewBox%3D%270%200%20600%20476%27%3E%3Crect%20width%3D%27600%27%20height%3D%273476%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Close-UP-Zauberer.jpg\" alt=\"Close UP Zauberer \" \/><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27476%27%20viewBox%3D%270%200%20600%20476%27%3E%3Crect%20width%3D%27600%27%20height%3D%273476%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Zaubershows.jpg\" alt=\"Zaubershows \" \/><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27442%27%20viewBox%3D%270%200%20600%20442%27%3E%3Crect%20width%3D%27600%27%20height%3D%273442%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Entertainer.jpg\" alt=\"Entertainer \" \/><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27442%27%20viewBox%3D%270%200%20600%20442%27%3E%3Crect%20width%3D%27600%27%20height%3D%273442%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Alleinunterhalter.jpg\" alt=\"Alleinunterhalter \" \/><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27458%27%20viewBox%3D%270%200%20600%20458%27%3E%3Crect%20width%3D%27600%27%20height%3D%273458%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Kinderzauberer.jpg\" alt=\"Kinderzauberer im Raum  Tann\" \/><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27458%27%20viewBox%3D%270%200%20600%20458%27%3E%3Crect%20width%3D%27600%27%20height%3D%273458%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Kinderzauberei.jpg\" alt=\"Kinderzauberei \" \/><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27458%27%20viewBox%3D%270%200%20600%20458%27%3E%3Crect%20width%3D%27600%27%20height%3D%273458%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Geburtstagszauberer.jpg\" alt=\"Geburtstagszauberer im Raum  Tann\" \/><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27458%27%20viewBox%3D%270%200%20600%20458%27%3E%3Crect%20width%3D%27600%27%20height%3D%273458%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Geburtstagszauberei.jpg\" alt=\"Geburtstagszauberei im Raum  Tann\" \/><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27480%27%20viewBox%3D%270%200%20600%20480%27%3E%3Crect%20width%3D%27600%27%20height%3D%273480%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Tischzauberer.jpg\" alt=\"Tischzauberer \" \/><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27480%27%20viewBox%3D%270%200%20600%20480%27%3E%3Crect%20width%3D%27600%27%20height%3D%273480%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Saalzauberer.jpg\" alt=\"Saalzauberer bei  Tann\" \/><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27560%27%20viewBox%3D%270%200%20600%20560%27%3E%3Crect%20width%3D%27600%27%20height%3D%273560%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Showkuenstler.jpg\" alt=\"Showkuenstler bei  Tann\" \/><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27560%27%20viewBox%3D%270%200%20600%20560%27%3E%3Crect%20width%3D%27600%27%20height%3D%273560%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Tischzauberei.jpg\" alt=\"Tischzauberei \" \/><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27477%27%20viewBox%3D%270%200%20600%20477%27%3E%3Crect%20width%3D%27600%27%20height%3D%273477%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Saalzauberei.jpg\" alt=\"Saalzauberei bei 84367 Tann\" \/><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27477%27%20viewBox%3D%270%200%20600%20477%27%3E%3Crect%20width%3D%27600%27%20height%3D%273477%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Zauber-Show.jpg\" alt=\"Zauber Show \" \/><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27462%27%20viewBox%3D%270%200%20600%20462%27%3E%3Crect%20width%3D%27600%27%20height%3D%273462%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Zauberer-mieten.jpg\" alt=\"Zauberer Mieten in der N&auml;he von 84367 Tann\" \/><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27462%27%20viewBox%3D%270%200%20600%20462%27%3E%3Crect%20width%3D%27600%27%20height%3D%273462%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Zauberer-fuer-Geburstag.jpg\" alt=\"Zauberer fuer Geburstag in der N&auml;he von  Tann\" \/><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27472%27%20viewBox%3D%270%200%20600%20472%27%3E%3Crect%20width%3D%27600%27%20height%3D%273472%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Zauber-Kuenstler.jpg\" alt=\"Zauber K&uuml;nstler im Raum 84367 Tann\" \/><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27472%27%20viewBox%3D%270%200%20600%20472%27%3E%3Crect%20width%3D%27600%27%20height%3D%273472%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Zauberer-Vorstellung.jpg\" alt=\"Zauberer Vorstellung f&uuml;r  Tann\" \/><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27460%27%20viewBox%3D%270%200%20600%20460%27%3E%3Crect%20width%3D%27600%27%20height%3D%273460%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Zauberer-Firmenfeier.jpg\" alt=\"Zauberer Firmenfeier f&uuml;r  Tann\" \/><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27460%27%20viewBox%3D%270%200%20600%20460%27%3E%3Crect%20width%3D%27600%27%20height%3D%273460%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-content\/uploads\/2020\/11\/Magic-Dinner.jpg\" alt=\"Magic Dinner \" \/>\n<\/div><div class=\"nav fusion-mobile-tab-nav\"><ul class=\"nav-tabs nav-justified\"><li><a class=\"tab-link\" data-toggle=\"tab\" id=\"mobile-fusion-tab-&nbsp;\" href=\"#tab-1852904ea5c591b1979\"><h4 class=\"fusion-tab-heading\">&nbsp;<\/h4><\/a><\/li><\/ul><\/div><div class=\"tab-pane fade fusion-clearfix\" id=\"tab-1852904ea5c591b1979\">\n<p><b>&#128270; Zaubershow, Zauberei, Zaubervorstellung und Zauberk&uuml;nstler und Zauberei Profi in Ihrer Region gegoogelt? &#10003; Wir freuen uns sehr &uuml;ber Ihren Besuch. &#9733;&#9733;&#9733;&#9733;&#9733; Werner Link, auch in 84367 Tann arbeiten wir f&uuml;r Sie. F&uuml;r Zauberer, sind wir Ihr Zauberk&uuml;nstler &#038; Magier. Zuverl&auml;ssigkeit zeichnet uns aus<\/b><\/p>\n<\/div><div class=\"nav fusion-mobile-tab-nav\"><ul class=\"nav-tabs nav-justified\"><li><a class=\"tab-link\" data-toggle=\"tab\" id=\"mobile-fusion-tab-&nbsp;\" href=\"#tab-3f5d29b1767f7726075\"><h4 class=\"fusion-tab-heading\">&nbsp;<\/h4><\/a><\/li><\/ul><\/div><div class=\"tab-pane fade fusion-clearfix\" id=\"tab-3f5d29b1767f7726075\">\n<h2>Zauberer in  Tann in Bayern: Wir von Werner Link sind Ihr Zauberk&uuml;nstler &#038; Magier! <\/h2>\n<ul>\n<li><a href=\"#Zauberk&uuml;nstler\">Zauberk&uuml;nstler<\/a><\/li>\n<li><a href=\"#Zauberei\">Zauberei<\/a><\/li>\n<li><a href=\"#Zaubershow\">Zaubershow<\/a><\/li>\n<li><a href=\"#Zaubervorstellung\">Zaubervorstellung<\/a><\/li>\n<\/ul>\n<h3>Close UP Zauberer f&uuml;r  Tann und &Ouml;dbinder, &Ouml;dweber, Osten, Pichl, Pilgram, Ras&ouml;d oder Kreil, N&uuml;rnberg, Obending?<\/h3>\n<h4>Werner Link, Ihr Zauberk&uuml;nstler &#038; Magier, Tischzauberer, Saalzauberer und Showk&uuml;nstler in  Tann &#8211; &Ouml;dbinder, &Ouml;dweber, Osten, Kreil, N&uuml;rnberg, Obending und Pichl, Pilgram, Ras&ouml;d f&uuml;r Zauberk&uuml;nstler und Magie &#038; Zauberei oder Zaubershow und zaubert f&uuml;r Kinder und Erwachsene.<\/h4>\n<ol>\n<li>Zaubershow, Magie, Shows  &#038; Illusionen <\/li>\n<li>Exklusive Zaubershows, zaubert f&uuml;r Kinder und Erwachsene<\/li>\n<li>Zauberk&uuml;nstler &#038; Magier, Private Feiern (Geburtstag, Hochzeit, Familienfest) <\/li>\n<li>Bezahlbare ZaubererAlleinunterhalter und Entertainer<\/li>\n<li>Zauberei, professioneller Zauberer &#038; Magier <\/li>\n<\/ol>\n<h2>Zauberer in  Tann, Wittibreut, Marktl, Erlbach, Julbach, Wurmannsquick, Kirchdorf (Inn) wie auch  Reut, Zeilarn, Stammham gesucht? Mit Werner Link haben Sie den richtigen Zauberk&uuml;nstler &#038; Magier f&uuml;r Zauberk&uuml;nstler in Ihrer N&auml;he gefunden.<\/h2>\n<p>Ebenso aus  Tann, Julbach, Wurmannsquick, Kirchdorf (Inn), Wittibreut, Marktl, Erlbach ebenso wie  Reut, Zeilarn, Stammham kann man leicht den &Uuml;berblick auf der Suche nach Experten verlieren. Aus einer Hand offeriert Ihnen unser Betrieb alles rund um Zauberer &#8211; G&uuml;nstig und optimal. Zaubervorstellung und Zauberk&uuml;nstler f&uuml;r wir dar&uuml;berhinaus ebenfalls bei Ihnen aus.<\/p>\n<h3>G&uuml;nstige Zauberk&uuml;nstler aus  Tann &Ouml;dbinder, &Ouml;dweber, Osten, Kreil, N&uuml;rnberg, Obending wie auch  Pichl, Pilgram, Ras&ouml;d -Sch&ouml;n dass Sie uns gefunden haben<\/h3>\n<p>Ihr Partner f&uuml;r Zauberer und Kinderzauberer &#038; Ballonk&uuml;nstler, Magie &#038; Zauberei wie auch Alleinunterhalter und Entertainer in  Tann &#8211; &Ouml;dbinder, &Ouml;dweber, Osten, Pichl, Pilgram, Ras&ouml;d und  Kreil, N&uuml;rnberg, Obending: Zauberk&uuml;nstler &#038; Magier Werner Link ist die richtige Adresse! In gro&szlig;er Auswahl und sehr gutem Preis-Leistung-Verh&auml;ltnis offerieren wir Ihnen sowohl Zaubershows und Zauberein als auch Zaubervorstellungen und Zauberk&uuml;nstler &#038; Magier f&uuml;r jeden Wunsch. <\/p>\n<h4>Vollkommen egal ob Sie nach Zauberer, Magie &#038; Zauberei, Alleinunterhalter und Entertainer, Kinderzauberer &#038; Ballonk&uuml;nstler, Zaubershows und Zauberein, Magie, Shows  &#038; Illusionen, Showk&uuml;nstler, professioneller Zauberer &#038; Magier, Zauberer f&uuml;r Feste und Firmenfeiern engagieren, zaubert f&uuml;r Kinder und Erwachsene, Mentalist &#038; Unterhalter, Zaubervorstellung sowie Firmenentertainer &#038; magisches Entertainment, Magischen Zirkel, Illusionisten \/ B&uuml;hnenzauberer, Zauberk&uuml;nstler &#038; Magier oder Private Feiern (Geburtstag, Hochzeit, Familienfest), Firmenfeiern (Weihnachtsfeier, Sommerfest, Firmenjubil&auml;um), Kundenevents (Hausmesse, Produktpr&auml;sentation uvm.)Private Feiern (Geburtstag, Hochzeit, Familienfest), Magic Dinner Abende, Wohnzimmerzaubershow gesucht haben -> Werner Link, Ihr Zauberk&uuml;nstler &#038; Magier f&uuml;r den Umkreis Tann<\/h4>\n<p><a name=\"Zaubervorstellung\"><\/p>\n<h2>Zaubervorstellungen, Sonderanfertigungen f&uuml;r  Tann.  <\/h2>\n\n<ol>\n<li>Firmenentertainer &#038; magisches Entertainment in 84367 Tann, Reut, Zeilarn, Stammham, Julbach, Wurmannsquick, Kirchdorf (Inn) und Wittibreut, Marktl, Erlbach<\/li>\n<li>Illusionisten \/ B&uuml;hnenzauberer EG, GRI, PAN, VIB<\/li>\n<li>Magischen Zirkel f&uuml;r  Tann &#8211; Kreil, N&uuml;rnberg, Obending, Pichl, Pilgram, Ras&ouml;d oder &Ouml;dbinder, &Ouml;dweber, Osten<\/li>\n<li>Individuelle Zaubervorstellungen<\/li>\n<li>Zaubervorstellung, Illusionisten \/ B&uuml;hnenzauberer wie auch Firmenentertainer &#038; magisches Entertainment, Magischen Zirkel<\/li>\n<\/ol>\n<p> \n<h2>Zaubervorstellung oder Zauberer in Tann gesucht? Werner Link ist Ihr Experte f&uuml;r Zauberk&uuml;nstler, Zaubervorstellungen und Zauberei<\/h2>\n\n<ol>\n<li>Zaubervorstellung, Illusionisten \/ B&uuml;hnenzauberer, Firmenentertainer &#038; magisches Entertainment, Magischen Zirkel<\/li>\n<li>Magischen Zirkel in  Tann, Wittibreut, Marktl, Erlbach, Julbach, Wurmannsquick, Kirchdorf (Inn) und Reut, Zeilarn, Stammham<\/li>\n<li>Illusionisten \/ B&uuml;hnenzauberer f&uuml;r  Tann &#8211; Pichl, Pilgram, Ras&ouml;d, Kreil, N&uuml;rnberg, Obending und &Ouml;dbinder, &Ouml;dweber, Osten<\/li>\n<li>Firmenentertainer &#038; magisches Entertainment <\/li>\n<\/ol>\n<p> \n\n<p>Durch unsere mehrj&auml;hrige Erfahrung in Zauberk&uuml;nstler k&ouml;nnen wir t&auml;glich eine z&uuml;gige und professionelle Umsetzung aller Arbeiten im Gebiet Zaubervorstellungen erm&ouml;glichen. Unsere gut ausgebildeten Besch&auml;ftigten verf&uuml;gen &uuml;ber gro&szlig;e Kenntnisse und F&auml;higkeiten im Fachgebiet Zaubervorstellungen und sind schnell bei Ihnen vor Ort. <\/p>\n\n\n<h2>Zaubervorstellungen, f&uuml;r  Tann sind ebenfalls Individualanfertigungen vorstellbar<\/h2>\n\n\n<p>Alleinig benutzen k&ouml;nnen Sie <strong>Zaubervorstellung, Illusionisten \/ B&uuml;hnenzauberer, Magischen Zirkel, Firmenentertainer &#038; magisches Entertainment<\/strong>, sofern es in einem Ma&szlig; gefertigt ist? Weiterhelfen k&ouml;nnen wir Ihnen hierbei. Nach Ma&szlig; produzieren wir unsre Zaubervorstellungen als erfahrene und professionelle Zauberk&uuml;nstler &#038; Magier an. Falls Sie sonst noch Individuelle W&uuml;nsche bei <cite>Zaubervorstellung, Illusionisten \/ B&uuml;hnenzauberer, Magischen Zirkel, Firmenentertainer &#038; magisches Entertainment<\/cite> haben, k&ouml;nnen Sie sich ebenfalls an uns wenden. Ihnen bieten wir unsre Zaubervorstellungen zu einem &uuml;beraus erfolgreichen Preis- \/ Leistungsverh&auml;ltnis an, obwohl die Zaubervorstellungen auf Traum Sonderanfertigungen sind.  <\/p>\n\n<a name=\"Zaubershow\"><\/p>\n<h2>Zaubershow: Immer die Qualit&auml;t im Blick! <\/h2>\n\n\n<h3>Zaubershow und Magie, Shows  &#038; Illusionen, Showk&uuml;nstler ebenso wie zaubert f&uuml;r Kinder und Erwachsene f&uuml;r  Tann gesucht? Ebenso f&uuml;r Magie, Shows  &#038; Illusionen, Showk&uuml;nstler und zaubert f&uuml;r Kinder und Erwachsene sind wir Ihr Partner<\/h3>\n\n\n<p>Von Zaubershow und Magie, Shows  &#038; Illusionen, Showk&uuml;nstler ebenso wie zaubert f&uuml;r Kinder und Erwachsene bieten wir Ihnen als erfahrener Zauberk&uuml;nstler &#038; Magier eine weit auseinander zerteilte <strong>Zaubershow und Showk&uuml;nstler, Magie, Shows  &#038; Illusionen und zaubert f&uuml;r Kinder und Erwachsene<\/strong> auswahl. Bei uns bekommen Sie Zaubershows in unterschiedlichen Gr&ouml;&szlig;en, Farben und Versionen. Wie Sie sie sich wollen, bieten wir Ihnen Zaubershows. Wir verstehen als professionelle Zauberk&uuml;nstler &#038; Magier, dass Sie Zaubershows in gro&szlig;er Auswahl w&uuml;nschen. Ein gro&szlig;es Angebot an Zaubershow und Magie, Shows  &#038; Illusionen, Showk&uuml;nstler oder zaubert f&uuml;r Kinder und Erwachsene halten wir also jedweden Tag f&uuml;r Sie bereit. Unsre Zaubershows sehen Sie sich ganz genau an, Sie werden besticht sein. <\/p>\n\n\n<h2>Zaubershow, optisch ansprechendes Design f&uuml;r  Tann.<\/h2>\n\n\n<p>Als kenntnisreicher Zauberk&uuml;nstler &#038; Magier von Zaubershow, zaubert f&uuml;r Kinder und Erwachsene, Magie, Shows  &#038; Illusionen, Showk&uuml;nstler bieten wir Ihnen eine breit gef&auml;cherte Auswahl.  Gr&ouml;&szlig;en, Farben und Ausf&uuml;hrungen &#8211; bei uns bekommen Sie Dienstleistungen, die darin verschieden sind.  Wie wollen Sie sich die Zaubershows, die wir Ihnen offerieren? Sie werden besticht sein, wenn Sie sich unsere Zaubershows ganz genau ansehen. <\/p>\n\n<a name=\"Zauberk&uuml;nstler\"><\/p>\n<h2>Zauberk&uuml;nstler &#038; Magier werden Ihnen von uns geboten<\/h2>\n\n \n\n<h2>Zauberk&uuml;nstler, Kundenevents (Hausmesse, Produktpr&auml;sentation uvm.)Private Feiern (Geburtstag, Hochzeit, Familienfest), Magic Dinner Abende, Wohnzimmerzaubershow und Firmenfeiern (Weihnachtsfeier, Sommerfest, Firmenjubil&auml;um), Private Feiern (Geburtstag, Hochzeit, Familienfest) in in 84367 Tann gesucht? Ebenfalls f&uuml;r Firmenfeiern (Weihnachtsfeier, Sommerfest, Firmenjubil&auml;um), Private Feiern (Geburtstag, Hochzeit, Familienfest) und Kundenevents (Hausmesse, Produktpr&auml;sentation uvm.)Private Feiern (Geburtstag, Hochzeit, Familienfest), Magic Dinner Abende, Wohnzimmerzaubershow sind wir Ihr Partner<\/h2>\n<ul>\n<li>Zauberk&uuml;nstler, Firmenfeiern (Weihnachtsfeier, Sommerfest, Firmenjubil&auml;um), Private Feiern (Geburtstag, Hochzeit, Familienfest) ebenso wie Kundenevents (Hausmesse, Produktpr&auml;sentation uvm.)Private Feiern (Geburtstag, Hochzeit, Familienfest), Magic Dinner Abende, Wohnzimmerzaubershow<\/li>\n<li>Kundenevents (Hausmesse, Produktpr&auml;sentation uvm.)Private Feiern (Geburtstag, Hochzeit, Familienfest), Magic Dinner Abende, Wohnzimmerzaubershow EG, GRI, PAN, VIB<\/li>\n<li>Firmenfeiern (Weihnachtsfeier, Sommerfest, Firmenjubil&auml;um)<\/li>\n<li>Individuelle Private Feiern (Geburtstag, Hochzeit, Familienfest)<\/li>\n<\/ul>\n\n<p>Zauberk&uuml;nstler, Kundenevents (Hausmesse, Produktpr&auml;sentation uvm.)Private Feiern (Geburtstag, Hochzeit, Familienfest), Magic Dinner Abende, Wohnzimmerzaubershow ebenso wie Firmenfeiern (Weihnachtsfeier, Sommerfest, Firmenjubil&auml;um), Private Feiern (Geburtstag, Hochzeit, Familienfest) ist einzigartig und in seiner Produktkategorie eines der besten Services der Zauberk&uuml;nstler &#038; Magier Reihe, die sie in Gesch&auml;ften erwerben werden.  Echt froh werden Sie sein.  Dadurch k&ouml;nne  Sie das. <\/p>\n\n\n<h2>Zauberk&uuml;nstler &#038; Magier, hohe Qualit&auml;tsma&szlig;st&auml;be f&uuml;r  Tann.<\/h2>\n\n\n<p>Ihnen offeriert unser g&uuml;tem&auml;&szlig;ig hochklassig gestaltetes Zauberk&uuml;nstler, Firmenfeiern (Weihnachtsfeier, Sommerfest, Firmenjubil&auml;um), Private Feiern (Geburtstag, Hochzeit, Familienfest) ebenso wie Kundenevents (Hausmesse, Produktpr&auml;sentation uvm.)Private Feiern (Geburtstag, Hochzeit, Familienfest), Magic Dinner Abende, Wohnzimmerzaubershow ein ausgezeichnetes Preis- \/ Leistungsverh&auml;ltnis. So konstruiert, dass Sie es &uuml;ber einen l&auml;ngeren Zeitraum hinweg nutzen k&ouml;nnen, sind unsere Zauberk&uuml;nstler &#038; Magier. Eine allerbeste Kombinierbarkeit kommt von Zauberk&uuml;nstler und Kundenevents (Hausmesse, Produktpr&auml;sentation uvm.)Private Feiern (Geburtstag, Hochzeit, Familienfest), Magic Dinner Abende, Wohnzimmerzaubershow oder Private Feiern (Geburtstag, Hochzeit, Familienfest), Firmenfeiern (Weihnachtsfeier, Sommerfest, Firmenjubil&auml;um) hinzu. Falls Sie sich davon selbst ein Bild machen m&ouml;chten, bieten wir Ihnen die Option, die Zauberk&uuml;nstler &#038; Magier bei uns in des Betriebes als kompetente Zauberk&uuml;nstler &#038; Magier eingehender anschauen zu k&ouml;nnen. Schauen Sie sich die Beschaffenheit von Zauberk&uuml;nstler, Kundenevents (Hausmesse, Produktpr&auml;sentation uvm.)Private Feiern (Geburtstag, Hochzeit, Familienfest), Magic Dinner Abende, Wohnzimmerzaubershow wie auch Private Feiern (Geburtstag, Hochzeit, Familienfest), Firmenfeiern (Weihnachtsfeier, Sommerfest, Firmenjubil&auml;um) ganz genau an und w&auml;hlen Sie Zauberk&uuml;nstler &#038; Magier aus, die ganz genau Ihren Bedarf erf&uuml;llen. <\/p>\n\n<a name=\"Zauberei\"><\/p>\n<h2>Luxus Zauberein ebenfalls in 84367 Tann!<\/h2>\n\n\n\n<h2>Zauberer und Zauberei in Tann gesucht? Werner Link ist Ihr Fachmann f&uuml;r Zauberk&uuml;nstler, Zauberk&uuml;nstler &#038; Magier sowie Zauberei<\/h2>\n\n \n\n<p>Zauberein k&ouml;nnen nur dann absolut in der Nutzung begeistern, wenn sie anpassbar gebaut sind. Finden Sie bei unsrem <strong>Zauberei und professioneller Zauberer &#038; Magier, Zauberer f&uuml;r Feste und Firmenfeiern engagieren ebenso wie Mentalist &#038; Unterhalter<\/strong> s&auml;mtliche M&ouml;glichkeiten, die Sie sich jederzeit gew&uuml;nscht haben. Unsre Zauberein, die die Anwendung bequem werden lassen, bieten Ihnen die kompetenten Bauarten. Selber &uuml;berzeugen Sie sich, welch gutes Preis- \/ Leistungsgef&uuml;ge Sie bei unserem <tt>Zauberei, professioneller Zauberer & Magier, Zauberer f&uuml;r Feste und Firmenfeiern engagieren, Mentalist & Unterhalter<\/tt> finden. Das <b>Zauberei, professioneller Zauberer &#038; Magier, Zauberer f&uuml;r Feste und Firmenfeiern engagieren oder Mentalist &#038; Unterhalter<\/b> ist ausgekl&uuml;gelt platziert, unsere Zauberein offerieren nicht nur Ihnen auch aller besten Komfort.<\/p>\n\n <\/p>\n<h3>Zauberein f&uuml;r  Tann, wir bieten vielf&auml;ltige Ausf&uuml;hrungen<\/h3>\n\n\n<h3>Sie haben einen Tanner Zauberk&uuml;nstler &#038; Magier aus dem Bereich 08572 gesucht?<\/h3>\n<p>M&ouml;chten Sie mehr erfahren? &#8211; Kontaktieren Sie uns  direkt in Tann &#8211; <strong>Tel.: 08572 358-215<\/strong><\/p>\n<h3>Die Angebote in  Tann (Bayern)<\/h3>\n<ul>\n  \n<li>Zauberk&uuml;nstler EG, GRI, PAN, VIB<\/li>\n\n<li>Zauberei in Bayern<\/li>\n<li>Zaubershow in  Tann &#8211; Pichl, Pilgram, Ras&ouml;d, Kreil, N&uuml;rnberg, Obending und &Ouml;dbinder, &Ouml;dweber, Osten<\/li>\n<p>  \n<li>Zaubervorstellung im Raum 84367, ,  \/ <\/li>\n\n<li>Zauberer aus  Tann, Reut, Zeilarn, Stammham, Wittibreut, Marktl, Erlbach oder Julbach, Wurmannsquick, Kirchdorf (Inn)<\/li>\n<li>Zauberk&uuml;nstler aus  Tann Haag, Felln, Denharten, Mauerwinkl, Stieglh&auml;usl, Eichhornseck, Hirschdobl, Breitenberg, Madlau, Ed, Jetzelsberg, Taubengrub, Dunz, Hammerstall, Kronwitten, Lichthub, Kreil, &Ouml;dweber, Reichzaun, Thal, Weizhof, Damreiher, &Ouml;dbinder, Egglhof, Dachgrub, Dorn, Simhar, Leipolds&ouml;d, Gilzau, Eiberg, Hiltraching, Burgstall, Giltshof, Tremmelhof, Holzau, Edgarten, Gigerenz, Ritzing, Stritzl&ouml;d, Schleindlsberg, Moosh&auml;usl, Furthh&auml;usl, Knogl, Henghub, Zimmern, H&ouml;rathal, Holzen, Lichtened, Weiherh&auml;usl, Steinbach, Reith, M&uuml;nzenhof, Kalteneck, Haghub, Steig, St&ouml;ckl, Forst, Biering, Aigner, Kollbach, Folgerberg, K&ouml;nigs&ouml;d, Ameringshub, Holzh&auml;user, Bernatz&ouml;d, Zoichl, Adelsberg, Haupold, Zaun, Krottenbach, Osten, Zimmerwaldh&auml;user, N&uuml;rnberg, Grasensee, Walburgskirchen, Eilham, Schachten, Hunddorf, Schnelling, Solling, Haberzagl, Hundsberg, Sp&ouml;ck, Scheften, Fraunleiten, Pichl, Nalling, Langeneck, Mautschneid, Hann&ouml;d, Grub, Obending, Asp&ouml;ck, Ras&ouml;d, Schmidhub, Inzenberg, Krumgassen, Holzbauer, Zoglau, Pilgram, Sch&uuml;&szlig;l&ouml;d, Simmerl, Forster<\/li>\n<\/ul>\n\n<\/div><\/div><\/div><div class=\"fusion-text\">\n<h4>Wissenswertes &uuml;ber Tann<\/h4>\n<div style=\"float:left; width: 80%;\">Tann&#8230; <\/p>\n<p><b>Tann<\/b> ist ein Markt im niederbayerischen Landkreis Rottal-Inn und der Sitz der Verwaltungsgemeinschaft Tann.<\/p>\n<\/div>\n<div style=\"float:right; width: 20%; text-align:center\"><img alt='Wappen des Marktes Tann' title='Wappen des Marktes Tann' src='\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/3\/38\/DEU_Tann_29_COA.svg\/140px-DEU_Tann_29_COA.svg.png' width='140' height='153' srcset='\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/3\/38\/DEU_Tann_29_COA.svg\/210px-DEU_Tann_29_COA.svg.png 1.5x, \/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/3\/38\/DEU_Tann_29_COA.svg\/280px-DEU_Tann_29_COA.svg.png 2x'><\/div>\n<div style=\"margin-top:150px\">\n<\/p>\n<blockquote>\n<p><b><a href=\"\/zauberer\/kontakt\/\">Schreiben Sie uns!<\/a><\/b><\/p>\n<\/blockquote>\n<\/div>\n<p><\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#129351; Werner Link, Ihr &#9989; Zauberk&uuml;nstler &#038; Magier f&uuml;r &#10042; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-827","post","type-post","status-publish","format-standard","hentry","category-local"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-json\/wp\/v2\/posts\/827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-json\/wp\/v2\/comments?post=827"}],"version-history":[{"count":0,"href":"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-json\/wp\/v2\/posts\/827\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-json\/wp\/v2\/media?parent=827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-json\/wp\/v2\/categories?post=827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.link-zauberkunst.de\/zauberer\/wp-json\/wp\/v2\/tags?post=827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}